{"id":17733,"date":"2024-03-01T09:03:21","date_gmt":"2024-03-01T09:03:21","guid":{"rendered":"https:\/\/safetykleenstg.wpengine.com\/?p=17733"},"modified":"2024-03-05T08:40:04","modified_gmt":"2024-03-05T08:40:04","slug":"ottimizzazione-del-processo-di-lavaggio-pezzi-per-stampa-3d-fdm-il-caso-di-fi-4-0","status":"publish","type":"post","link":"https:\/\/safetykleeninternational.com\/it\/ottimizzazione-del-processo-di-lavaggio-pezzi-per-stampa-3d-fdm-il-caso-di-fi-4-0\/","title":{"rendered":"Ottimizzazione del Processo di Lavaggio Pezzi per Stampa 3D FDM: Il Caso di Fi 4.0"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":42,"featured_media":17748,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":[],"meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"footnotes":""},"categories":[42],"tags":[],"funnel":[],"industry":[],"pillar":[],"class_list":["post-17733","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-case-studies-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ottimizzazione del Processo di Lavaggio Pezzi per Stampa 3D FDM: Il Caso di Fi 4.0 - Safetykleen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safetykleeninternational.com\/it\/ottimizzazione-del-processo-di-lavaggio-pezzi-per-stampa-3d-fdm-il-caso-di-fi-4-0\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ottimizzazione del Processo di Lavaggio Pezzi per Stampa 3D FDM: Il Caso di Fi 4.0 - Safetykleen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safetykleeninternational.com\/it\/ottimizzazione-del-processo-di-lavaggio-pezzi-per-stampa-3d-fdm-il-caso-di-fi-4-0\/\" \/>\n<meta property=\"og:site_name\" content=\"Safetykleen\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-01T09:03:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-05T08:40:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safetykleeninternational.com\/wp-content\/uploads\/2024\/03\/stampa-3d-print-fdm-macchina-1200large.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"502\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rosalba Zanghi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SafetykleenUK\" \/>\n<meta name=\"twitter:site\" content=\"@SafetykleenUK\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rosalba Zanghi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/it\\\/ottimizzazione-del-processo-di-lavaggio-pezzi-per-stampa-3d-fdm-il-caso-di-fi-4-0\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/it\\\/ottimizzazione-del-processo-di-lavaggio-pezzi-per-stampa-3d-fdm-il-caso-di-fi-4-0\\\/\"},\"author\":{\"name\":\"Rosalba Zanghi\",\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/it\\\/#\\\/schema\\\/person\\\/f6da57ad78f525ca7f3fc57c6d394a4e\"},\"headline\":\"Ottimizzazione del Processo di Lavaggio Pezzi per Stampa 3D FDM: Il Caso di Fi 4.0\",\"datePublished\":\"2024-03-01T09:03:21+00:00\",\"dateModified\":\"2024-03-05T08:40:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/it\\\/ottimizzazione-del-processo-di-lavaggio-pezzi-per-stampa-3d-fdm-il-caso-di-fi-4-0\\\/\"},\"wordCount\":14,\"publisher\":{\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/it\\\/ottimizzazione-del-processo-di-lavaggio-pezzi-per-stampa-3d-fdm-il-caso-di-fi-4-0\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/safetykleeninternational.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/stampa-3d-print-fdm-macchina-1200large.jpg\",\"articleSection\":[\"Case studies\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/it\\\/ottimizzazione-del-processo-di-lavaggio-pezzi-per-stampa-3d-fdm-il-caso-di-fi-4-0\\\/\",\"url\":\"https:\\\/\\\/safetykleeninternational.com\\\/it\\\/ottimizzazione-del-processo-di-lavaggio-pezzi-per-stampa-3d-fdm-il-caso-di-fi-4-0\\\/\",\"name\":\"Ottimizzazione del Processo di Lavaggio Pezzi per Stampa 3D FDM: Il Caso di Fi 4.0 - Safetykleen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/it\\\/ottimizzazione-del-processo-di-lavaggio-pezzi-per-stampa-3d-fdm-il-caso-di-fi-4-0\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/it\\\/ottimizzazione-del-processo-di-lavaggio-pezzi-per-stampa-3d-fdm-il-caso-di-fi-4-0\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/safetykleeninternational.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/stampa-3d-print-fdm-macchina-1200large.jpg\",\"datePublished\":\"2024-03-01T09:03:21+00:00\",\"dateModified\":\"2024-03-05T08:40:04+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/safetykleeninternational.com\\\/it\\\/ottimizzazione-del-processo-di-lavaggio-pezzi-per-stampa-3d-fdm-il-caso-di-fi-4-0\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/it\\\/ottimizzazione-del-processo-di-lavaggio-pezzi-per-stampa-3d-fdm-il-caso-di-fi-4-0\\\/#primaryimage\",\"url\":\"https:\\\/\\\/safetykleeninternational.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/stampa-3d-print-fdm-macchina-1200large.jpg\",\"contentUrl\":\"https:\\\/\\\/safetykleeninternational.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/stampa-3d-print-fdm-macchina-1200large.jpg\",\"width\":1200,\"height\":502,\"caption\":\"3D Printer (FDM)\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/safetykleeninternational.com\\\/it\\\/\",\"name\":\"Safetykleen\",\"description\":\"Parts Cleaning Services for Business &amp; Industry\",\"publisher\":{\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/safetykleeninternational.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/it\\\/#organization\",\"name\":\"Safetykleen\",\"url\":\"https:\\\/\\\/safetykleeninternational.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/safetykleeninternational.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Screen-Shot-2020-12-15-at-09.13.37.png\",\"contentUrl\":\"https:\\\/\\\/safetykleeninternational.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Screen-Shot-2020-12-15-at-09.13.37.png\",\"width\":628,\"height\":280,\"caption\":\"Safetykleen\"},\"image\":{\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/SafetykleenUK\",\"https:\\\/\\\/www.instagram.com\\\/safetykleeninternational\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/safetykleen\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCWA-lHlJu6XDHKtNszhebFA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/it\\\/#\\\/schema\\\/person\\\/f6da57ad78f525ca7f3fc57c6d394a4e\",\"name\":\"Rosalba Zanghi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f571694df76ed37a3e16efe4b332da7af364f4ecb07f0f0d902c96911355b3e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f571694df76ed37a3e16efe4b332da7af364f4ecb07f0f0d902c96911355b3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f571694df76ed37a3e16efe4b332da7af364f4ecb07f0f0d902c96911355b3e?s=96&d=mm&r=g\",\"caption\":\"Rosalba Zanghi\"},\"sameAs\":[\"https:\\\/\\\/safetykleeninternational.com\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ottimizzazione del Processo di Lavaggio Pezzi per Stampa 3D FDM: Il Caso di Fi 4.0 - Safetykleen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safetykleeninternational.com\/it\/ottimizzazione-del-processo-di-lavaggio-pezzi-per-stampa-3d-fdm-il-caso-di-fi-4-0\/","og_locale":"it_IT","og_type":"article","og_title":"Ottimizzazione del Processo di Lavaggio Pezzi per Stampa 3D FDM: Il Caso di Fi 4.0 - Safetykleen","og_url":"https:\/\/safetykleeninternational.com\/it\/ottimizzazione-del-processo-di-lavaggio-pezzi-per-stampa-3d-fdm-il-caso-di-fi-4-0\/","og_site_name":"Safetykleen","article_published_time":"2024-03-01T09:03:21+00:00","article_modified_time":"2024-03-05T08:40:04+00:00","og_image":[{"width":1200,"height":502,"url":"https:\/\/safetykleeninternational.com\/wp-content\/uploads\/2024\/03\/stampa-3d-print-fdm-macchina-1200large.jpg","type":"image\/jpeg"}],"author":"Rosalba Zanghi","twitter_card":"summary_large_image","twitter_creator":"@SafetykleenUK","twitter_site":"@SafetykleenUK","twitter_misc":{"Scritto da":"Rosalba Zanghi","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safetykleeninternational.com\/it\/ottimizzazione-del-processo-di-lavaggio-pezzi-per-stampa-3d-fdm-il-caso-di-fi-4-0\/#article","isPartOf":{"@id":"https:\/\/safetykleeninternational.com\/it\/ottimizzazione-del-processo-di-lavaggio-pezzi-per-stampa-3d-fdm-il-caso-di-fi-4-0\/"},"author":{"name":"Rosalba Zanghi","@id":"https:\/\/safetykleeninternational.com\/it\/#\/schema\/person\/f6da57ad78f525ca7f3fc57c6d394a4e"},"headline":"Ottimizzazione del Processo di Lavaggio Pezzi per Stampa 3D FDM: Il Caso di Fi 4.0","datePublished":"2024-03-01T09:03:21+00:00","dateModified":"2024-03-05T08:40:04+00:00","mainEntityOfPage":{"@id":"https:\/\/safetykleeninternational.com\/it\/ottimizzazione-del-processo-di-lavaggio-pezzi-per-stampa-3d-fdm-il-caso-di-fi-4-0\/"},"wordCount":14,"publisher":{"@id":"https:\/\/safetykleeninternational.com\/it\/#organization"},"image":{"@id":"https:\/\/safetykleeninternational.com\/it\/ottimizzazione-del-processo-di-lavaggio-pezzi-per-stampa-3d-fdm-il-caso-di-fi-4-0\/#primaryimage"},"thumbnailUrl":"https:\/\/safetykleeninternational.com\/wp-content\/uploads\/2024\/03\/stampa-3d-print-fdm-macchina-1200large.jpg","articleSection":["Case studies"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/safetykleeninternational.com\/it\/ottimizzazione-del-processo-di-lavaggio-pezzi-per-stampa-3d-fdm-il-caso-di-fi-4-0\/","url":"https:\/\/safetykleeninternational.com\/it\/ottimizzazione-del-processo-di-lavaggio-pezzi-per-stampa-3d-fdm-il-caso-di-fi-4-0\/","name":"Ottimizzazione del Processo di Lavaggio Pezzi per Stampa 3D FDM: Il Caso di Fi 4.0 - Safetykleen","isPartOf":{"@id":"https:\/\/safetykleeninternational.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safetykleeninternational.com\/it\/ottimizzazione-del-processo-di-lavaggio-pezzi-per-stampa-3d-fdm-il-caso-di-fi-4-0\/#primaryimage"},"image":{"@id":"https:\/\/safetykleeninternational.com\/it\/ottimizzazione-del-processo-di-lavaggio-pezzi-per-stampa-3d-fdm-il-caso-di-fi-4-0\/#primaryimage"},"thumbnailUrl":"https:\/\/safetykleeninternational.com\/wp-content\/uploads\/2024\/03\/stampa-3d-print-fdm-macchina-1200large.jpg","datePublished":"2024-03-01T09:03:21+00:00","dateModified":"2024-03-05T08:40:04+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safetykleeninternational.com\/it\/ottimizzazione-del-processo-di-lavaggio-pezzi-per-stampa-3d-fdm-il-caso-di-fi-4-0\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/safetykleeninternational.com\/it\/ottimizzazione-del-processo-di-lavaggio-pezzi-per-stampa-3d-fdm-il-caso-di-fi-4-0\/#primaryimage","url":"https:\/\/safetykleeninternational.com\/wp-content\/uploads\/2024\/03\/stampa-3d-print-fdm-macchina-1200large.jpg","contentUrl":"https:\/\/safetykleeninternational.com\/wp-content\/uploads\/2024\/03\/stampa-3d-print-fdm-macchina-1200large.jpg","width":1200,"height":502,"caption":"3D Printer (FDM)"},{"@type":"WebSite","@id":"https:\/\/safetykleeninternational.com\/it\/#website","url":"https:\/\/safetykleeninternational.com\/it\/","name":"Safetykleen","description":"Parts Cleaning Services for Business &amp; Industry","publisher":{"@id":"https:\/\/safetykleeninternational.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safetykleeninternational.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/safetykleeninternational.com\/it\/#organization","name":"Safetykleen","url":"https:\/\/safetykleeninternational.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/safetykleeninternational.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/safetykleeninternational.com\/wp-content\/uploads\/2020\/12\/Screen-Shot-2020-12-15-at-09.13.37.png","contentUrl":"https:\/\/safetykleeninternational.com\/wp-content\/uploads\/2020\/12\/Screen-Shot-2020-12-15-at-09.13.37.png","width":628,"height":280,"caption":"Safetykleen"},"image":{"@id":"https:\/\/safetykleeninternational.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/SafetykleenUK","https:\/\/www.instagram.com\/safetykleeninternational\/","https:\/\/www.linkedin.com\/company\/safetykleen\/","https:\/\/www.youtube.com\/channel\/UCWA-lHlJu6XDHKtNszhebFA"]},{"@type":"Person","@id":"https:\/\/safetykleeninternational.com\/it\/#\/schema\/person\/f6da57ad78f525ca7f3fc57c6d394a4e","name":"Rosalba Zanghi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/9f571694df76ed37a3e16efe4b332da7af364f4ecb07f0f0d902c96911355b3e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9f571694df76ed37a3e16efe4b332da7af364f4ecb07f0f0d902c96911355b3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9f571694df76ed37a3e16efe4b332da7af364f4ecb07f0f0d902c96911355b3e?s=96&d=mm&r=g","caption":"Rosalba Zanghi"},"sameAs":["https:\/\/safetykleeninternational.com\/"]}]}},"_links":{"self":[{"href":"https:\/\/safetykleeninternational.com\/it\/wp-json\/wp\/v2\/posts\/17733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safetykleeninternational.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safetykleeninternational.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safetykleeninternational.com\/it\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/safetykleeninternational.com\/it\/wp-json\/wp\/v2\/comments?post=17733"}],"version-history":[{"count":0,"href":"https:\/\/safetykleeninternational.com\/it\/wp-json\/wp\/v2\/posts\/17733\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safetykleeninternational.com\/it\/wp-json\/wp\/v2\/media\/17748"}],"wp:attachment":[{"href":"https:\/\/safetykleeninternational.com\/it\/wp-json\/wp\/v2\/media?parent=17733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safetykleeninternational.com\/it\/wp-json\/wp\/v2\/categories?post=17733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safetykleeninternational.com\/it\/wp-json\/wp\/v2\/tags?post=17733"},{"taxonomy":"format","embeddable":true,"href":"https:\/\/safetykleeninternational.com\/it\/wp-json\/wp\/v2\/format?post=17733"},{"taxonomy":"funnel","embeddable":true,"href":"https:\/\/safetykleeninternational.com\/it\/wp-json\/wp\/v2\/funnel?post=17733"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/safetykleeninternational.com\/it\/wp-json\/wp\/v2\/industry?post=17733"},{"taxonomy":"pillar","embeddable":true,"href":"https:\/\/safetykleeninternational.com\/it\/wp-json\/wp\/v2\/pillar?post=17733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}