{"id":7697,"date":"2022-03-30T13:26:27","date_gmt":"2022-03-30T13:26:27","guid":{"rendered":"https:\/\/safetykleenstg.wpengine.com\/produits\/applications-chimiques\/liquidi-per-lavapistole\/prodotti-base-acqua-per-lavapistole\/"},"modified":"2022-11-08T16:37:01","modified_gmt":"2022-11-08T16:37:01","slug":"produits-base-aqueuse-nettoyeurs-pistolets","status":"publish","type":"page","link":"https:\/\/safetykleeninternational.com\/fr\/produits\/applications-chimiques\/liquides-pistolets-peinture\/produits-base-aqueuse-nettoyeurs-pistolets\/","title":{"rendered":"Produits \u00e0 base aqueuse pour les nettoyeurs de pistolets"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":7709,"parent":7691,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","format":[],"meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"footnotes":""},"funnel":[],"industry":[],"pillar":[],"searchcategory":[],"class_list":["post-7697","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Produits \u00e0 base aqueuse pour les nettoyeurs de pistolets - Safetykleen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safetykleeninternational.com\/fr\/produits\/applications-chimiques\/liquides-pistolets-peinture\/produits-base-aqueuse-nettoyeurs-pistolets\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Produits \u00e0 base aqueuse pour les nettoyeurs de pistolets - Safetykleen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safetykleeninternational.com\/fr\/produits\/applications-chimiques\/liquides-pistolets-peinture\/produits-base-aqueuse-nettoyeurs-pistolets\/\" \/>\n<meta property=\"og:site_name\" content=\"Safetykleen\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-08T16:37:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safetykleeninternational.com\/wp-content\/uploads\/2022\/02\/spray-gun-painting-paint-equipment-pistola-spruzzo-vernice-lavapistole-verniciatura-1200-opposite.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"801\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@SafetykleenUK\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr\\\/produits\\\/applications-chimiques\\\/liquides-pistolets-peinture\\\/produits-base-aqueuse-nettoyeurs-pistolets\\\/\",\"url\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr\\\/produits\\\/applications-chimiques\\\/liquides-pistolets-peinture\\\/produits-base-aqueuse-nettoyeurs-pistolets\\\/\",\"name\":\"Produits \u00e0 base aqueuse pour les nettoyeurs de pistolets - Safetykleen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr\\\/produits\\\/applications-chimiques\\\/liquides-pistolets-peinture\\\/produits-base-aqueuse-nettoyeurs-pistolets\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr\\\/produits\\\/applications-chimiques\\\/liquides-pistolets-peinture\\\/produits-base-aqueuse-nettoyeurs-pistolets\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/safetykleeninternational.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/spray-gun-painting-paint-equipment-pistola-spruzzo-vernice-lavapistole-verniciatura-1200-opposite.jpg\",\"datePublished\":\"2022-03-30T13:26:27+00:00\",\"dateModified\":\"2022-11-08T16:37:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr\\\/produits\\\/applications-chimiques\\\/liquides-pistolets-peinture\\\/produits-base-aqueuse-nettoyeurs-pistolets\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/safetykleeninternational.com\\\/fr\\\/produits\\\/applications-chimiques\\\/liquides-pistolets-peinture\\\/produits-base-aqueuse-nettoyeurs-pistolets\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr\\\/produits\\\/applications-chimiques\\\/liquides-pistolets-peinture\\\/produits-base-aqueuse-nettoyeurs-pistolets\\\/#primaryimage\",\"url\":\"https:\\\/\\\/safetykleeninternational.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/spray-gun-painting-paint-equipment-pistola-spruzzo-vernice-lavapistole-verniciatura-1200-opposite.jpg\",\"contentUrl\":\"https:\\\/\\\/safetykleeninternational.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/spray-gun-painting-paint-equipment-pistola-spruzzo-vernice-lavapistole-verniciatura-1200-opposite.jpg\",\"width\":1200,\"height\":801,\"caption\":\"automobile repairman painter hand in protective glove with airbrush pulverizer painting car body in paint chamber\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr\\\/produits\\\/applications-chimiques\\\/liquides-pistolets-peinture\\\/produits-base-aqueuse-nettoyeurs-pistolets\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits Chimiques pour le Nettoyage Industriel\",\"item\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr\\\/products\\\/cleaning-chemistries\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Liquides pour les nettoyeurs de pistolets de peinture\",\"item\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr\\\/products\\\/cleaning-chemistries\\\/spray-gun-cleaner-liquids\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Produits \u00e0 base aqueuse pour les nettoyeurs de pistolets\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr\\\/\",\"name\":\"Safetykleen\",\"description\":\"Parts Cleaning Services for Business &amp; Industry\",\"publisher\":{\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr\\\/#organization\",\"name\":\"Safetykleen\",\"url\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/safetykleeninternational.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Screen-Shot-2020-12-15-at-09.13.37.png\",\"contentUrl\":\"https:\\\/\\\/safetykleeninternational.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Screen-Shot-2020-12-15-at-09.13.37.png\",\"width\":628,\"height\":280,\"caption\":\"Safetykleen\"},\"image\":{\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/SafetykleenUK\",\"https:\\\/\\\/www.instagram.com\\\/safetykleeninternational\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/safetykleen\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCWA-lHlJu6XDHKtNszhebFA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Produits \u00e0 base aqueuse pour les nettoyeurs de pistolets - Safetykleen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safetykleeninternational.com\/fr\/produits\/applications-chimiques\/liquides-pistolets-peinture\/produits-base-aqueuse-nettoyeurs-pistolets\/","og_locale":"fr_FR","og_type":"article","og_title":"Produits \u00e0 base aqueuse pour les nettoyeurs de pistolets - Safetykleen","og_url":"https:\/\/safetykleeninternational.com\/fr\/produits\/applications-chimiques\/liquides-pistolets-peinture\/produits-base-aqueuse-nettoyeurs-pistolets\/","og_site_name":"Safetykleen","article_modified_time":"2022-11-08T16:37:01+00:00","og_image":[{"width":1200,"height":801,"url":"https:\/\/safetykleeninternational.com\/wp-content\/uploads\/2022\/02\/spray-gun-painting-paint-equipment-pistola-spruzzo-vernice-lavapistole-verniciatura-1200-opposite.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@SafetykleenUK","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/safetykleeninternational.com\/fr\/produits\/applications-chimiques\/liquides-pistolets-peinture\/produits-base-aqueuse-nettoyeurs-pistolets\/","url":"https:\/\/safetykleeninternational.com\/fr\/produits\/applications-chimiques\/liquides-pistolets-peinture\/produits-base-aqueuse-nettoyeurs-pistolets\/","name":"Produits \u00e0 base aqueuse pour les nettoyeurs de pistolets - Safetykleen","isPartOf":{"@id":"https:\/\/safetykleeninternational.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safetykleeninternational.com\/fr\/produits\/applications-chimiques\/liquides-pistolets-peinture\/produits-base-aqueuse-nettoyeurs-pistolets\/#primaryimage"},"image":{"@id":"https:\/\/safetykleeninternational.com\/fr\/produits\/applications-chimiques\/liquides-pistolets-peinture\/produits-base-aqueuse-nettoyeurs-pistolets\/#primaryimage"},"thumbnailUrl":"https:\/\/safetykleeninternational.com\/wp-content\/uploads\/2022\/02\/spray-gun-painting-paint-equipment-pistola-spruzzo-vernice-lavapistole-verniciatura-1200-opposite.jpg","datePublished":"2022-03-30T13:26:27+00:00","dateModified":"2022-11-08T16:37:01+00:00","breadcrumb":{"@id":"https:\/\/safetykleeninternational.com\/fr\/produits\/applications-chimiques\/liquides-pistolets-peinture\/produits-base-aqueuse-nettoyeurs-pistolets\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safetykleeninternational.com\/fr\/produits\/applications-chimiques\/liquides-pistolets-peinture\/produits-base-aqueuse-nettoyeurs-pistolets\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/safetykleeninternational.com\/fr\/produits\/applications-chimiques\/liquides-pistolets-peinture\/produits-base-aqueuse-nettoyeurs-pistolets\/#primaryimage","url":"https:\/\/safetykleeninternational.com\/wp-content\/uploads\/2022\/02\/spray-gun-painting-paint-equipment-pistola-spruzzo-vernice-lavapistole-verniciatura-1200-opposite.jpg","contentUrl":"https:\/\/safetykleeninternational.com\/wp-content\/uploads\/2022\/02\/spray-gun-painting-paint-equipment-pistola-spruzzo-vernice-lavapistole-verniciatura-1200-opposite.jpg","width":1200,"height":801,"caption":"automobile repairman painter hand in protective glove with airbrush pulverizer painting car body in paint chamber"},{"@type":"BreadcrumbList","@id":"https:\/\/safetykleeninternational.com\/fr\/produits\/applications-chimiques\/liquides-pistolets-peinture\/produits-base-aqueuse-nettoyeurs-pistolets\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Produits","item":"https:\/\/safetykleeninternational.com\/fr\/products\/"},{"@type":"ListItem","position":2,"name":"Produits Chimiques pour le Nettoyage Industriel","item":"https:\/\/safetykleeninternational.com\/fr\/products\/cleaning-chemistries\/"},{"@type":"ListItem","position":3,"name":"Liquides pour les nettoyeurs de pistolets de peinture","item":"https:\/\/safetykleeninternational.com\/fr\/products\/cleaning-chemistries\/spray-gun-cleaner-liquids\/"},{"@type":"ListItem","position":4,"name":"Produits \u00e0 base aqueuse pour les nettoyeurs de pistolets"}]},{"@type":"WebSite","@id":"https:\/\/safetykleeninternational.com\/fr\/#website","url":"https:\/\/safetykleeninternational.com\/fr\/","name":"Safetykleen","description":"Parts Cleaning Services for Business &amp; Industry","publisher":{"@id":"https:\/\/safetykleeninternational.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safetykleeninternational.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/safetykleeninternational.com\/fr\/#organization","name":"Safetykleen","url":"https:\/\/safetykleeninternational.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/safetykleeninternational.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/safetykleeninternational.com\/wp-content\/uploads\/2020\/12\/Screen-Shot-2020-12-15-at-09.13.37.png","contentUrl":"https:\/\/safetykleeninternational.com\/wp-content\/uploads\/2020\/12\/Screen-Shot-2020-12-15-at-09.13.37.png","width":628,"height":280,"caption":"Safetykleen"},"image":{"@id":"https:\/\/safetykleeninternational.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/SafetykleenUK","https:\/\/www.instagram.com\/safetykleeninternational\/","https:\/\/www.linkedin.com\/company\/safetykleen\/","https:\/\/www.youtube.com\/channel\/UCWA-lHlJu6XDHKtNszhebFA"]}]}},"_links":{"self":[{"href":"https:\/\/safetykleeninternational.com\/fr\/wp-json\/wp\/v2\/pages\/7697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safetykleeninternational.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/safetykleeninternational.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/safetykleeninternational.com\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/safetykleeninternational.com\/fr\/wp-json\/wp\/v2\/comments?post=7697"}],"version-history":[{"count":0,"href":"https:\/\/safetykleeninternational.com\/fr\/wp-json\/wp\/v2\/pages\/7697\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/safetykleeninternational.com\/fr\/wp-json\/wp\/v2\/pages\/7691"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safetykleeninternational.com\/fr\/wp-json\/wp\/v2\/media\/7709"}],"wp:attachment":[{"href":"https:\/\/safetykleeninternational.com\/fr\/wp-json\/wp\/v2\/media?parent=7697"}],"wp:term":[{"taxonomy":"format","embeddable":true,"href":"https:\/\/safetykleeninternational.com\/fr\/wp-json\/wp\/v2\/format?post=7697"},{"taxonomy":"funnel","embeddable":true,"href":"https:\/\/safetykleeninternational.com\/fr\/wp-json\/wp\/v2\/funnel?post=7697"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/safetykleeninternational.com\/fr\/wp-json\/wp\/v2\/industry?post=7697"},{"taxonomy":"pillar","embeddable":true,"href":"https:\/\/safetykleeninternational.com\/fr\/wp-json\/wp\/v2\/pillar?post=7697"},{"taxonomy":"searchcategory","embeddable":true,"href":"https:\/\/safetykleeninternational.com\/fr\/wp-json\/wp\/v2\/searchcategory?post=7697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}