{"id":22615,"date":"2024-08-19T13:39:49","date_gmt":"2024-08-19T13:39:49","guid":{"rendered":"https:\/\/safetykleenstg.wpengine.com\/services\/nettoyage-automatique-lessiviel-2\/"},"modified":"2024-11-19T15:12:17","modified_gmt":"2024-11-19T15:12:17","slug":"nettoyage-automatique-lessiviel","status":"publish","type":"page","link":"https:\/\/safetykleeninternational.com\/fr-be\/services\/nettoyage-automatique-lessiviel\/","title":{"rendered":"Nettoyage Automatique Lessiviel"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":37,"featured_media":21001,"parent":22506,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"","format":[],"meta":{"_acf_changed":false,"footnotes":""},"funnel":[],"industry":[],"pillar":[],"searchcategory":[],"class_list":["post-22615","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nettoyage Automatique Lessiviel - Safetykleen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safetykleeninternational.com\/fr-be\/services\/nettoyage-automatique-lessiviel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nettoyage Automatique Lessiviel - Safetykleen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safetykleeninternational.com\/fr-be\/services\/nettoyage-automatique-lessiviel\/\" \/>\n<meta property=\"og:site_name\" content=\"Safetykleen\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-19T15:12:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safetykleeninternational.com\/wp-content\/uploads\/2021\/03\/M312_Customer_0375.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@SafetykleenUK\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr-be\\\/services\\\/nettoyage-automatique-lessiviel\\\/\",\"url\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr-be\\\/services\\\/nettoyage-automatique-lessiviel\\\/\",\"name\":\"Nettoyage Automatique Lessiviel - Safetykleen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr-be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr-be\\\/services\\\/nettoyage-automatique-lessiviel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr-be\\\/services\\\/nettoyage-automatique-lessiviel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/safetykleeninternational.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/M312_Customer_0375.jpg\",\"datePublished\":\"2024-08-19T13:39:49+00:00\",\"dateModified\":\"2024-11-19T15:12:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr-be\\\/services\\\/nettoyage-automatique-lessiviel\\\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/safetykleeninternational.com\\\/fr-be\\\/services\\\/nettoyage-automatique-lessiviel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr-be\\\/services\\\/nettoyage-automatique-lessiviel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/safetykleeninternational.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/M312_Customer_0375.jpg\",\"contentUrl\":\"https:\\\/\\\/safetykleeninternational.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/M312_Customer_0375.jpg\",\"width\":8256,\"height\":5504,\"caption\":\"Mann an Ultraschallreiniger Sonickleen Eco von Safetykleen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr-be\\\/services\\\/nettoyage-automatique-lessiviel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Services\",\"item\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr-be\\\/services\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nettoyage Automatique Lessiviel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr-be\\\/#website\",\"url\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr-be\\\/\",\"name\":\"Safetykleen\",\"description\":\"Parts Cleaning Services for Business &amp; Industry\",\"publisher\":{\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr-be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr-be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr-be\\\/#organization\",\"name\":\"Safetykleen\",\"url\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr-be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr-be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/safetykleeninternational.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Screen-Shot-2020-12-15-at-09.13.37.png\",\"contentUrl\":\"https:\\\/\\\/safetykleeninternational.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Screen-Shot-2020-12-15-at-09.13.37.png\",\"width\":628,\"height\":280,\"caption\":\"Safetykleen\"},\"image\":{\"@id\":\"https:\\\/\\\/safetykleeninternational.com\\\/fr-be\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/SafetykleenUK\",\"https:\\\/\\\/www.instagram.com\\\/safetykleeninternational\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/safetykleen\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCWA-lHlJu6XDHKtNszhebFA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nettoyage Automatique Lessiviel - Safetykleen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safetykleeninternational.com\/fr-be\/services\/nettoyage-automatique-lessiviel\/","og_locale":"fr_FR","og_type":"article","og_title":"Nettoyage Automatique Lessiviel - Safetykleen","og_url":"https:\/\/safetykleeninternational.com\/fr-be\/services\/nettoyage-automatique-lessiviel\/","og_site_name":"Safetykleen","article_modified_time":"2024-11-19T15:12:17+00:00","og_image":[{"url":"https:\/\/safetykleeninternational.com\/wp-content\/uploads\/2021\/03\/M312_Customer_0375.jpg","width":1024,"height":683,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@SafetykleenUK","twitter_misc":{"Dur\u00e9e de lecture est.":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/safetykleeninternational.com\/fr-be\/services\/nettoyage-automatique-lessiviel\/","url":"https:\/\/safetykleeninternational.com\/fr-be\/services\/nettoyage-automatique-lessiviel\/","name":"Nettoyage Automatique Lessiviel - Safetykleen","isPartOf":{"@id":"https:\/\/safetykleeninternational.com\/fr-be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safetykleeninternational.com\/fr-be\/services\/nettoyage-automatique-lessiviel\/#primaryimage"},"image":{"@id":"https:\/\/safetykleeninternational.com\/fr-be\/services\/nettoyage-automatique-lessiviel\/#primaryimage"},"thumbnailUrl":"https:\/\/safetykleeninternational.com\/wp-content\/uploads\/2021\/03\/M312_Customer_0375.jpg","datePublished":"2024-08-19T13:39:49+00:00","dateModified":"2024-11-19T15:12:17+00:00","breadcrumb":{"@id":"https:\/\/safetykleeninternational.com\/fr-be\/services\/nettoyage-automatique-lessiviel\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safetykleeninternational.com\/fr-be\/services\/nettoyage-automatique-lessiviel\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/safetykleeninternational.com\/fr-be\/services\/nettoyage-automatique-lessiviel\/#primaryimage","url":"https:\/\/safetykleeninternational.com\/wp-content\/uploads\/2021\/03\/M312_Customer_0375.jpg","contentUrl":"https:\/\/safetykleeninternational.com\/wp-content\/uploads\/2021\/03\/M312_Customer_0375.jpg","width":8256,"height":5504,"caption":"Mann an Ultraschallreiniger Sonickleen Eco von Safetykleen"},{"@type":"BreadcrumbList","@id":"https:\/\/safetykleeninternational.com\/fr-be\/services\/nettoyage-automatique-lessiviel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Services","item":"https:\/\/safetykleeninternational.com\/fr-be\/services\/"},{"@type":"ListItem","position":2,"name":"Nettoyage Automatique Lessiviel"}]},{"@type":"WebSite","@id":"https:\/\/safetykleeninternational.com\/fr-be\/#website","url":"https:\/\/safetykleeninternational.com\/fr-be\/","name":"Safetykleen","description":"Parts Cleaning Services for Business &amp; Industry","publisher":{"@id":"https:\/\/safetykleeninternational.com\/fr-be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safetykleeninternational.com\/fr-be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Organization","@id":"https:\/\/safetykleeninternational.com\/fr-be\/#organization","name":"Safetykleen","url":"https:\/\/safetykleeninternational.com\/fr-be\/","logo":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/safetykleeninternational.com\/fr-be\/#\/schema\/logo\/image\/","url":"https:\/\/safetykleeninternational.com\/wp-content\/uploads\/2020\/12\/Screen-Shot-2020-12-15-at-09.13.37.png","contentUrl":"https:\/\/safetykleeninternational.com\/wp-content\/uploads\/2020\/12\/Screen-Shot-2020-12-15-at-09.13.37.png","width":628,"height":280,"caption":"Safetykleen"},"image":{"@id":"https:\/\/safetykleeninternational.com\/fr-be\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/SafetykleenUK","https:\/\/www.instagram.com\/safetykleeninternational\/","https:\/\/www.linkedin.com\/company\/safetykleen\/","https:\/\/www.youtube.com\/channel\/UCWA-lHlJu6XDHKtNszhebFA"]}]}},"_links":{"self":[{"href":"https:\/\/safetykleeninternational.com\/fr-be\/wp-json\/wp\/v2\/pages\/22615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safetykleeninternational.com\/fr-be\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/safetykleeninternational.com\/fr-be\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/safetykleeninternational.com\/fr-be\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/safetykleeninternational.com\/fr-be\/wp-json\/wp\/v2\/comments?post=22615"}],"version-history":[{"count":0,"href":"https:\/\/safetykleeninternational.com\/fr-be\/wp-json\/wp\/v2\/pages\/22615\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/safetykleeninternational.com\/fr-be\/wp-json\/wp\/v2\/pages\/22506"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safetykleeninternational.com\/fr-be\/wp-json\/wp\/v2\/media\/21001"}],"wp:attachment":[{"href":"https:\/\/safetykleeninternational.com\/fr-be\/wp-json\/wp\/v2\/media?parent=22615"}],"wp:term":[{"taxonomy":"format","embeddable":true,"href":"https:\/\/safetykleeninternational.com\/fr-be\/wp-json\/wp\/v2\/format?post=22615"},{"taxonomy":"funnel","embeddable":true,"href":"https:\/\/safetykleeninternational.com\/fr-be\/wp-json\/wp\/v2\/funnel?post=22615"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/safetykleeninternational.com\/fr-be\/wp-json\/wp\/v2\/industry?post=22615"},{"taxonomy":"pillar","embeddable":true,"href":"https:\/\/safetykleeninternational.com\/fr-be\/wp-json\/wp\/v2\/pillar?post=22615"},{"taxonomy":"searchcategory","embeddable":true,"href":"https:\/\/safetykleeninternational.com\/fr-be\/wp-json\/wp\/v2\/searchcategory?post=22615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}